{"id":26415,"date":"2022-04-02T15:50:50","date_gmt":"2022-04-02T21:50:50","guid":{"rendered":"https:\/\/stemcells.suwebcr.com\/el-stem-cells-transplant-institute-en-bahamas\/"},"modified":"2022-04-18T22:07:00","modified_gmt":"2022-04-19T04:07:00","slug":"stem-cells-transplant-institute-en-bahamas","status":"publish","type":"page","link":"https:\/\/stemcells.suwebcr.com\/es\/stem-cells-transplant-institute-en-bahamas\/","title":{"rendered":"Stem Cells Transplant Institute en Bahamas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26415\" class=\"elementor elementor-26415 elementor-25693\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24bae8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24bae8c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7e334d\" data-id=\"f7e334d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac7586f elementor-widget elementor-widget-heading\" data-id=\"ac7586f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Stem Cells Transplant Institute en Bahamas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04fbe13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04fbe13\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f96b36\" data-id=\"0f96b36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-640d4fd elementor-widget elementor-widget-text-editor\" data-id=\"640d4fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Bienvenidos al <em>Stem Cells Transplant Institute<\/em> en Bahamas. Nuestra misi\u00f3n es brindar un tratamiento de primer nivel a los pacientes que utilizan terapia con C\u00e9lulas Madre.<\/h3><p>Nuestra cl\u00ednica en Costa Rica, est\u00e1 dirigida por el Doctor Leslie Mes\u00e9n, uno de los m\u00e9dicos expertos m\u00e1s destacados en terapia con C\u00e9lulas Madre. Sabemos que tenemos la capacidad para ofrecer el mismo nivel de atenci\u00f3n y experiencia en las Bahamas.<\/p><p>Creemos que la terapia con C\u00e9lulas Madre tiene el potencial de tratar una amplia gama de condiciones m\u00e9dicas y estamos comprometidos a brindarles a nuestros pacientes el mejor tratamiento posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d8705f7\" data-id=\"d8705f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c61cf76 elementor-widget elementor-widget-image\" data-id=\"c61cf76\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"260\" height=\"256\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/stemcellslogo.png\" class=\"attachment-large size-large wp-image-10066\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f96966f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f96966f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b5f839\" data-id=\"7b5f839\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-980164f elementor-widget elementor-widget-heading\" data-id=\"980164f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfEn qu\u00e9 consiste la terapia con C\u00e9lulas Madre?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-501ad04 elementor-widget elementor-widget-text-editor\" data-id=\"501ad04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa terapia con C\u00e9lulas Madre se utiliza para tratar o prevenir enfermedades. Las C\u00e9lulas Madre son c\u00e9lulas no especializadas que pueden convertirse en cualquier tipo de c\u00e9lula del cuerpo. Se pueden encontrar en embriones, fetos y adultos.\r\n\r\nLas terapias que utilizan C\u00e9lulas Madre de embriones se denominan terapias con C\u00e9lulas Madre Embrionarias. Y, las terapias que utilizan C\u00e9lulas Madre de adultos, se denominan terapias con C\u00e9lulas Madre de Adultos.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64fa54e\" data-id=\"64fa54e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00c3c04 elementor-widget elementor-widget-image\" data-id=\"00c3c04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/stemcells2.jpg\" class=\"attachment-large size-large wp-image-10063\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/stemcells2.jpg 840w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/stemcells2-300x200.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/stemcells2-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f4f9ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f4f9ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2db8e4d\" data-id=\"2db8e4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7e5e00 elementor-widget elementor-widget-heading\" data-id=\"d7e5e00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 usar C\u00e9lulas Madre?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e89a45 elementor-widget elementor-widget-text-editor\" data-id=\"8e89a45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLas C\u00e9lulas Madre tienen el potencial de tratar o prevenir una amplia gama de enfermedades. Se pueden usar para reemplazar c\u00e9lulas, tejidos y \u00f3rganos da\u00f1ados o destruidos.\r\n\r\nSe ha descubierto que m\u00e1s de 150 enfermedades pueden tratarse con la terapia de C\u00e9lulas Madre, incluida la enfermedad de Alzheimer, enfermedades card\u00edacas, accidentes cerebrovasculares, Diabetes Mellitus, Enfermedad Pulmonar Obstructiva Cr\u00f3nica (EPOC), \u00falceras en los pies que no cicatrizan (\u00falceras del pie diab\u00e9tico) , Ceguera (retinosis pigmentaria) y enfermedades de la sangre (c\u00e1nceres hematopoy\u00e9ticos).\r\n\r\nLas C\u00e9lulas Madre pueden reparar el da\u00f1o a los \u00f3rganos y tejidos con un menor riesgo de rechazo en comparaci\u00f3n con los trasplantes de \u00f3rganos.\r\n\r\nAdem\u00e1s, la terapia con C\u00e9lulas Madre se puede considerar como un tratamiento cosm\u00e9tico o m\u00e9dico electivo, cuando no hay evidencia de un proceso de enfermedad.\r\n\r\nAqu\u00ed en <em>Stem Cells Transplant Institute<\/em>, ofrecemos muchos tratamientos con C\u00e9lulas Madre para ayudar a los pacientes con una serie de afecciones, que incluyen la enfermedad de Alzheimer, el Autismo, la Diabetes, la Osteoartritis y la EPOC, entre otros.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-072826c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"072826c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2ac122\" data-id=\"c2ac122\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fab1bce elementor-widget elementor-widget-heading\" data-id=\"fab1bce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tratamientos con c\u00e9lulas madre disponibles en Bahamas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-24264a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24264a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ae30fc\" data-id=\"3ae30fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3037cd2 elementor-widget elementor-widget-image\" data-id=\"3037cd2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/04\/The-Ultimate-Guide-on-Autism-Spectrum-Disorder.jpg\" class=\"attachment-large size-large wp-image-19814\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/04\/The-Ultimate-Guide-on-Autism-Spectrum-Disorder.jpg 1000w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/04\/The-Ultimate-Guide-on-Autism-Spectrum-Disorder-300x200.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/04\/The-Ultimate-Guide-on-Autism-Spectrum-Disorder-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f61669d\" data-id=\"f61669d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-826133c elementor-widget elementor-widget-text-editor\" data-id=\"826133c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Autismo<\/strong><\/h3>\r\nEl Autismo es un trastorno del desarrollo, que afecta la forma en que una persona se comunica e interact\u00faa con los dem\u00e1s. Tambi\u00e9n puede causar problemas con el aprendizaje del comportamiento y la atenci\u00f3n. No existe una cura conocida para el Autismo, pero existen tratamientos que pueden ayudar a mejorar los s\u00edntomas. Un tratamiento que puede ser \u00fatil para los pacientes autistas es la terapia con C\u00e9lulas Madre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-02d82b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02d82b0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-34ab262\" data-id=\"34ab262\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-209e8a2 elementor-widget elementor-widget-image\" data-id=\"209e8a2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/Diabetes-type-1-treatment-with-stem-cells.jpg\" class=\"attachment-large size-large wp-image-8724\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/Diabetes-type-1-treatment-with-stem-cells.jpg 450w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/Diabetes-type-1-treatment-with-stem-cells-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72d3a6c\" data-id=\"72d3a6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0ffdb6 elementor-widget elementor-widget-text-editor\" data-id=\"e0ffdb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Diabetes Tipo 1 y 2<\/h3>\r\nSe ha visto que las C\u00e9lulas Madre son efectivas en el tratamiento para la Diabetes Tipo 1 y 2. Para proporcionar una descripci\u00f3n general r\u00e1pida: en el tipo 1, el P\u00e1ncreas no produce suficiente insulina para controlar los niveles de az\u00facar en la sangre. En el tipo 2, el P\u00e1ncreas produce insulina, pero las c\u00e9lulas no reaccionan ni responden bien a ella.\r\n\r\nLos tratamientos con C\u00e9lulas Madre se realizan mediante la recolecci\u00f3n de m\u00e9dula \u00f3sea de la pelvis o el hueso de la cadera del donante y la extracci\u00f3n de C\u00e9lulas Madre Mesenquimales (MSC). \u00a0Las C\u00e9lulas Madre se utilizan para tratar a pacientes con Diabetes Tipo 1 y 2, porque pueden convertirse en c\u00e9lulas beta productoras de insulina. Se ha demostrado que estos tratamientos con C\u00e9lulas Madre, mejoran los niveles de az\u00facar en la sangre y reducen la necesidad de terapia con insulina.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91d06bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91d06bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c60abbc\" data-id=\"c60abbc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a31e21e elementor-widget elementor-widget-image\" data-id=\"a31e21e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"549\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/06\/Osteoarthritis-Stem-Cells-treatment.jpg\" class=\"attachment-large size-large wp-image-5097\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/06\/Osteoarthritis-Stem-Cells-treatment.jpg 732w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/06\/Osteoarthritis-Stem-Cells-treatment-300x225.jpg 300w\" sizes=\"(max-width: 732px) 100vw, 732px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e198d90\" data-id=\"e198d90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3740fe elementor-widget elementor-widget-text-editor\" data-id=\"b3740fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Osteoartritis<\/h3>\r\nLa Osteoartritis es una condici\u00f3n que a menudo afecta las articulaciones, especialmente las de las manos. Tambi\u00e9n puede afectar la columna vertebral, las caderas, las rodillas, los hombros u otras articulaciones. Hay muchos tratamientos diferentes para la Osteoartritis que generalmente difieren seg\u00fan la gravedad de los s\u00edntomas y si se padece en m\u00e1s de una articulaci\u00f3n.\r\n\r\nUna opci\u00f3n de tratamiento para la Osteoartritis es la terapia con C\u00e9lulas Madre. \u00c9stas han demostrado ser beneficiosas para ayudar a reparar el da\u00f1o al tejido del cart\u00edlago. Tambi\u00e9n pueden ayudar a reducir la inflamaci\u00f3n y el dolor alrededor de la articulaci\u00f3n. Este tratamiento se ha utilizado con \u00e9xito en pacientes que no desean enfrentarse a una cirug\u00eda o se est\u00e1n recuperando de una operaci\u00f3n, como la cirug\u00eda de reemplazo de cadera.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f967a7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f967a7f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6cf6ac1\" data-id=\"6cf6ac1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55b7c18 elementor-widget elementor-widget-image\" data-id=\"55b7c18\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"350\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/alzheimers-stem-cells-treatment.jpg\" class=\"attachment-large size-large wp-image-8604\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/alzheimers-stem-cells-treatment.jpg 500w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/alzheimers-stem-cells-treatment-300x210.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec20f9a\" data-id=\"ec20f9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1475c55 elementor-widget elementor-widget-text-editor\" data-id=\"1475c55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>La enfermedad de Alzheimer<\/h3>\r\nLa enfermedad de Alzheimer es una enfermedad neurodegenerativa que causa problemas de memoria, pensamiento y comportamiento. Es la forma m\u00e1s com\u00fan de demencia, un grupo de enfermedades que provocan una disminuci\u00f3n de la funci\u00f3n cerebral. La enfermedad de Alzheimer afecta a unos 5,7 millones de estadounidenses y es la sexta causa principal de muerte en los Estados Unidos.\r\n\r\nNo existe, a\u00fan, una cura para la enfermedad de Alzheimer, aunque existen tratamientos disponibles que pueden ayudar a mejorar los s\u00edntomas. Uno de esos tratamientos es la terapia con C\u00e9lulas Madre. Se ha demostrado que \u00e9stas, ayudan a proteger el cerebro del da\u00f1o y promueven el crecimiento de nuevas neuronas. Tambi\u00e9n pueden ayudar a reducir la inflamaci\u00f3n y mejorar la funci\u00f3n cognitiva.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d7782d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7782d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-048b80b\" data-id=\"048b80b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94fec88 elementor-widget elementor-widget-image\" data-id=\"94fec88\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/COPD-Treatment-1024x681.jpg\" class=\"attachment-large size-large wp-image-5128\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/COPD-Treatment-1024x681.jpg 1024w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/COPD-Treatment-300x199.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/COPD-Treatment-768x510.jpg 768w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/COPD-Treatment.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f76399\" data-id=\"5f76399\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf6016e elementor-widget elementor-widget-text-editor\" data-id=\"bf6016e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Enfermedad Pulmonar Obstructiva Cr\u00f3nica<\/h3>\r\nLa Enfermedad Pulmonar Obstructiva Cr\u00f3nica (EPOC), es una enfermedad que da\u00f1a gradualmente los pulmones y las v\u00edas respiratorias. Puede derivar en complicaciones de salud graves. La EPOC es la tercera causa principal de muerte en los Estados Unidos, despu\u00e9s de las enfermedades card\u00edacas y el c\u00e1ncer.\u00a0Hay varios tratamientos diferentes disponibles para la EPOC, incluida la terapia con C\u00e9lulas Madre, que se han comprobado efectivas para combatir la inflamaci\u00f3n pulmonar y reducir el da\u00f1o al tejido pulmonar.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a612ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a612ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b4a5bc8\" data-id=\"b4a5bc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f89b7 elementor-widget elementor-widget-image\" data-id=\"64f89b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/erectile-dysfunction-stem-cells-therapy.jpg\" class=\"attachment-large size-large wp-image-7720\" alt=\"erectile dysfunction stem cells therapy\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/erectile-dysfunction-stem-cells-therapy.jpg 450w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/erectile-dysfunction-stem-cells-therapy-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37f25dc\" data-id=\"37f25dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55a9580 elementor-widget elementor-widget-text-editor\" data-id=\"55a9580\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Disfunci\u00f3n Er\u00e9ctil<\/h3>\r\nLa Disfunci\u00f3n Er\u00e9ctil es una condici\u00f3n en la que un hombre tiene problemas para lograr o mantener una erecci\u00f3n. Por lo general, afecta a las personas mayores, pero tambi\u00e9n pueden padecerla los hombres m\u00e1s j\u00f3venes. La Disfunci\u00f3n Er\u00e9ctil puede ser causada por varios motivos: un flujo sangu\u00edneo deficiente en el pene, una lesi\u00f3n en la columna vertebral o la regi\u00f3n p\u00e9lvica, ciertos medicamentos y diversas afecciones de salud. Algunos hombres pueden no notar ning\u00fan s\u00edntoma hasta que experimentan problemas de Disfunci\u00f3n Er\u00e9ctil.\r\n\r\nUn tipo com\u00fan de tratamiento es el de C\u00e9lulas Madre, que se han visto como una terapia prometedora, demostrando la capacidad para ayudar a aumentar el flujo sangu\u00edneo. \u00a0Se utilizan c\u00e9lulas testiculares, para ayudar a mejorar la funci\u00f3n y el flujo sangu\u00edneo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33c0b1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33c0b1e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cb9ccd\" data-id=\"7cb9ccd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da13772 elementor-widget elementor-widget-image\" data-id=\"da13772\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/multiple-scherosis.jpg\" class=\"attachment-large size-large wp-image-13507\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/multiple-scherosis.jpg 1000w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/multiple-scherosis-300x200.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/multiple-scherosis-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a14c71\" data-id=\"2a14c71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dae49c5 elementor-widget elementor-widget-text-editor\" data-id=\"dae49c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Esclerosis M\u00faltiple<\/strong><\/h3>\r\nLa Esclerosis M\u00faltiple (EM) es una enfermedad en la que el sistema inmunitario da\u00f1a las vainas de mielina de las c\u00e9lulas nerviosas del cerebro y la m\u00e9dula espinal. Esto ralentiza los mensajes hacia y desde el cerebro, lo que afecta el control muscular, la coordinaci\u00f3n, las sensaciones, el pensamiento y otras funciones b\u00e1sicas.\r\n\r\nAlgunos tratamientos para la EM incluyen la terapia con C\u00e9lulas Madre, que ayuda a protegernos de la enfermedad, promoviendo nuevas c\u00e9lulas nerviosas. Tambi\u00e9n colabora reduciendo la inflamaci\u00f3n y en la prevenci\u00f3n de los da\u00f1os causados por dicha enfermedad.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2c46f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2c46f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3acc94b\" data-id=\"3acc94b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-361ba7f elementor-widget elementor-widget-image\" data-id=\"361ba7f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/Detection-of-parkinsons.jpg\" class=\"attachment-large size-large wp-image-5272\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/Detection-of-parkinsons.jpg 840w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/Detection-of-parkinsons-300x200.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/07\/Detection-of-parkinsons-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26f0765\" data-id=\"26f0765\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c95f59b elementor-widget elementor-widget-text-editor\" data-id=\"c95f59b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Enfermedad de Parkinson<\/h3>\r\nLa enfermedad de Parkinson es una de tipo neurodegenerativa, que afecta al sistema nervioso. Es una enfermedad progresiva, lo que significa que empeora con el tiempo. Los s\u00edntomas de la enfermedad de Parkinson incluyen temblores, rigidez y problemas de movimiento.\r\n\r\nNo existe una cura para la enfermedad de Parkinson, aunque existen tratamientos disponibles que pueden ayudar a mejorar los s\u00edntomas. Uno de esos tratamientos es la terapia con C\u00e9lulas Madre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a63746c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a63746c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-81bd4f1\" data-id=\"81bd4f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dc06d0 elementor-widget elementor-widget-image\" data-id=\"2dc06d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/rheumatoid-arthritis-stem-cells-therapy.jpg\" class=\"attachment-large size-large wp-image-7761\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/rheumatoid-arthritis-stem-cells-therapy.jpg 640w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/rheumatoid-arthritis-stem-cells-therapy-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b9f352\" data-id=\"3b9f352\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-409cb2a elementor-widget elementor-widget-text-editor\" data-id=\"409cb2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Artritis Reumatoide<\/h3>\r\nLa Artritis Reumatoide es una enfermedad autoinmune cr\u00f3nica, que causa la inflamaci\u00f3n de las articulaciones. Afecta a millones de estadounidenses y no se ha encontrado la cura a\u00fan. El tratamiento para la Artritis Reumatoide incluye la terapia con C\u00e9lulas Madre. \u00c9stas, son eficaces para combatir la inflamaci\u00f3n y reducir el da\u00f1o del tejido pulmonar.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5a6dd6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a6dd6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dd76f4a\" data-id=\"dd76f4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93c22a2 elementor-widget elementor-widget-image\" data-id=\"93c22a2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"649\" height=\"438\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/03\/anti-aging-vs-cenegenics.jpg\" class=\"attachment-large size-large wp-image-6439\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/03\/anti-aging-vs-cenegenics.jpg 649w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/03\/anti-aging-vs-cenegenics-300x202.jpg 300w\" sizes=\"(max-width: 649px) 100vw, 649px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f431337\" data-id=\"f431337\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4356ba elementor-widget elementor-widget-text-editor\" data-id=\"b4356ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Anti envejecimiento<\/h3>\r\nA medida que las personas envejecen, sus c\u00e9lulas tambi\u00e9n lo hacen. Esto puede conducir a una serie de problemas, incluida una disminuci\u00f3n en la funci\u00f3n de las c\u00e9lulas y un aumento en el riesgo de la enfermedad. No existe una cura para el envejecimiento, aunque s\u00ed existen tratamientos disponibles que pueden ayudar a retrasar el proceso. Uno de esos tratamientos es la terapia con C\u00e9lulas Madre.\r\n\r\nLas C\u00e9lulas Madre son eficaces para combatir los efectos del envejecimiento. Protejen las c\u00e9lulas, promueven el crecimiento de nuevas c\u00e9lulas, lo que ayuda a mejorar las funciones y reducir el riesgo de enfermedades.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-02795c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02795c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fbcd6d\" data-id=\"2fbcd6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e198119 elementor-widget elementor-widget-image\" data-id=\"e198119\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/peripheral-neuropathy-treatment-near-me.jpg\" class=\"attachment-large size-large wp-image-8078\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/peripheral-neuropathy-treatment-near-me.jpg 450w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/peripheral-neuropathy-treatment-near-me-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37ccfbf\" data-id=\"37ccfbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43765b2 elementor-widget elementor-widget-text-editor\" data-id=\"43765b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Neuropat\u00eda<\/h3>\r\nLa neuropat\u00eda es una condici\u00f3n que causa da\u00f1o a los nervios del cuerpo. Puede afectar muchas partes diferentes, incluidos los brazos y las piernas. Afecciones como la Diabetes, la presi\u00f3n arterial alta y el abuso del alcohol pueden aumentar el riesgo de padecer una Neuropat\u00eda. La neuropat\u00eda puede causar dolor, entumecimiento, hormigueo o sensaci\u00f3n de ardor, debilidad muscular o par\u00e1lisis.\r\n\r\nExisten varios tratamientos para la Neuropat\u00eda, incluida la terapia con C\u00e9lulas Madre. \u00c9stas, son eficaces para combatir el dolor neurop\u00e1tico y reducir la cantidad de medicamentos necesarios para controlar los s\u00edntomas, del 30 % con los tratamientos tradicionales a solo el 10 % con los tratamientos con C\u00e9lulas Madre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c10ee2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c10ee2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fb2d836\" data-id=\"fb2d836\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16e4eec elementor-widget elementor-widget-image\" data-id=\"16e4eec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"350\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/08\/Why-Type-2-Diabetes-Increases-the-Risk-of-Cardiovascular-Disease.jpeg\" class=\"attachment-large size-large wp-image-5394\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/08\/Why-Type-2-Diabetes-Increases-the-Risk-of-Cardiovascular-Disease.jpeg 590w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2018\/08\/Why-Type-2-Diabetes-Increases-the-Risk-of-Cardiovascular-Disease-300x178.jpeg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9efd82e\" data-id=\"9efd82e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8373a6 elementor-widget elementor-widget-text-editor\" data-id=\"b8373a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Enfermedad Cardiovascular<\/h3>\r\nLa enfermedad Cardiovascular es una de las principales causas de enfermedad y muerte en los Estados Unidos. La enfermedad cardiovascular implica un conjunto de problemas de salud que pueden afectar el coraz\u00f3n, los vasos sangu\u00edneos o la circulaci\u00f3n. Hay tratamientos disponibles para pacientes con enfermedades cardiovasculares, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nLas C\u00e9lulas Madre son eficaces para combatir los efectos de las enfermedades Cardiovasculares. Tambi\u00e9n pueden ayudar a reducir la acumulaci\u00f3n de placa en las arterias y mejorar la circulaci\u00f3n, al ayudar a que el coraz\u00f3n da\u00f1ado funcione mejor.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-02a9f2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02a9f2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a3bd3f\" data-id=\"9a3bd3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b8771e elementor-widget elementor-widget-image\" data-id=\"6b8771e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"190\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/chest-pain-or-heart-attack-1136-300x190.jpg\" class=\"attachment-large size-large wp-image-8286\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2d3917b\" data-id=\"2d3917b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32d1b4e elementor-widget elementor-widget-text-editor\" data-id=\"32d1b4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Infarto de Miocardio<\/h3>\r\nEl Infarto de Miocardio, tambi\u00e9n conocido como \u201cataque card\u00edaco\u201d, es una afecci\u00f3n en la que se da\u00f1a el m\u00fasculo card\u00edaco. Este da\u00f1o puede provocar una serie de complicaciones, que incluyen dolor en el pecho, insuficiencia card\u00edaca, latidos card\u00edacos irregulares y ataques card\u00edacos. Hay muchos tratamientos disponibles para las personas diagnosticadas con Infarto de Miocardio, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que dichas c\u00e9lulas son eficaces para combatir los efectos del Infarto de Miocardio. Pueden ayudar a mejorar la funci\u00f3n card\u00edaca y reducir el riesgo de complicaciones.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-930fbe5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"930fbe5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86bf103\" data-id=\"86bf103\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be6dd55 elementor-widget elementor-widget-image\" data-id=\"be6dd55\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Stem-Cells-for-Cerebral-Artery-Ischemic-Stroke.jpg\" class=\"attachment-large size-large wp-image-10846\" alt=\"Stem Cells for Cerebral Artery Ischemic Stroke\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Stem-Cells-for-Cerebral-Artery-Ischemic-Stroke.jpg 900w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Stem-Cells-for-Cerebral-Artery-Ischemic-Stroke-300x200.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Stem-Cells-for-Cerebral-Artery-Ischemic-Stroke-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dfd55dc\" data-id=\"dfd55dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5475fa6 elementor-widget elementor-widget-text-editor\" data-id=\"5475fa6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Isquemia Critica de las Extremidades<\/h3>\r\nLa Isquemia Cr\u00edtica de las Extremidades (CLI, por sus siglas en ingl\u00e9s) es una afecci\u00f3n en la que se reduce o bloquea el flujo de sangre a las extremidades. Esto puede provocar dolor, hinchaz\u00f3n y \u00falceras en la piel. Si el paciente no se ocupa, puede derivar en una gangrena y amputaci\u00f3n. Hay tratamientos disponibles como la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que las C\u00e9lulas Madre son efectivas para combatir los efectos de la Isquemia Cr\u00edtica de las Extremidades. Puede ayudar a mejorar el flujo de sangre en el \u00e1rea afectada.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2747df5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2747df5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6afbfe\" data-id=\"c6afbfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2946219 elementor-widget elementor-widget-image\" data-id=\"2946219\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/rotatorcuff.jpg\" class=\"attachment-large size-large wp-image-13243\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/rotatorcuff.jpg 768w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2020\/01\/rotatorcuff-300x200.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-067f7fd\" data-id=\"067f7fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aba764 elementor-widget elementor-widget-text-editor\" data-id=\"0aba764\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Manguito rotador<\/h3>\r\nEl Manguito Rotador es un grupo de m\u00fasculos y tendones que ayudan a levantar el brazo. Puede lesionarse o da\u00f1arse, lo que causa dolor, debilidad y un rango de movimiento limitado. Hay muchos tratamientos disponibles para las personas diagnosticadas con lesi\u00f3n del Manguito de los Rotadores, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que son eficaces para combatir los efectos de las lesiones del Manguito de los Rotadores. Y que ayuda a mejorar la funci\u00f3n muscular y reducir el riesgo de complicaciones.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fdbe46d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdbe46d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b7f2665\" data-id=\"b7f2665\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1cec71 elementor-widget elementor-widget-image\" data-id=\"c1cec71\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Degenerative_Disc_Disease-1024x576.jpg\" class=\"attachment-large size-large wp-image-10791\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Degenerative_Disc_Disease.jpg 1024w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Degenerative_Disc_Disease-300x169.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/09\/Degenerative_Disc_Disease-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cfca2b7\" data-id=\"cfca2b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d5308e elementor-widget elementor-widget-text-editor\" data-id=\"7d5308e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Enfermedad Degenerativa de Disco<\/h3>\r\nLa Enfermedad Degenerativa de Disco, es una condici\u00f3n en la que los discos entre las v\u00e9rtebras se rompen, causando dolor y movilidad limitada. Hay muchos tratamientos disponibles para las personas diagnosticadas con esta enfermedad, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que son eficaces para combatir la Enfermedad Degenerativa de Disco. Las C\u00e9lulas Madre pueden ayudar a reducir el dolor y mejorar la movilidad.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a65efdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a65efdc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-69256ce\" data-id=\"69256ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd33906 elementor-widget elementor-widget-image\" data-id=\"fd33906\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"466\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/spinalcord.jpg\" class=\"attachment-large size-large wp-image-8398\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/spinalcord.jpg 650w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/05\/spinalcord-300x215.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f84e84d\" data-id=\"f84e84d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8022dd0 elementor-widget elementor-widget-text-editor\" data-id=\"8022dd0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Lesiones de la M\u00e9dula Espinal<\/h3>\r\nLas Lesiones de la M\u00e9dula Espinal pueden causar una amplia gama de s\u00edntomas, seg\u00fan el nivel y la gravedad de la lesi\u00f3n. El paciente puede sentir dolor, entumecimiento, hormigueo, debilidad, par\u00e1lisis e incontinencia. Hay muchos tratamientos disponibles para las personas diagnosticadas con una Lesi\u00f3n de la M\u00e9dula Espinal, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que las C\u00e9lulas Madre son eficaces para combatir los efectos de las Lesiones de la M\u00e9dula Espinal. Pueden ayudar a mejorar la funci\u00f3n y reducir el riesgo de complicaciones. Incluso se est\u00e1n utilizando algunos tratamientos con C\u00e9lulas Madre para ayudar a los pacientes a caminar de nuevo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c47678e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c47678e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9eef43f\" data-id=\"9eef43f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d3023 elementor-widget elementor-widget-image\" data-id=\"42d3023\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"470\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/Amyotrophic-Lateral-Sclerosis.jpg\" class=\"attachment-large size-large wp-image-10352\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/Amyotrophic-Lateral-Sclerosis.jpg 650w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/08\/Amyotrophic-Lateral-Sclerosis-300x217.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f029fa\" data-id=\"0f029fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7ab93d elementor-widget elementor-widget-text-editor\" data-id=\"a7ab93d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Esclerosis Lateral Amiotr\u00f3fica (ELA)<\/h3>\r\nLa Esclerosis Lateral Amiotr\u00f3fica, es una enfermedad neurodegenerativa progresiva que afecta las c\u00e9lulas nerviosas del cerebro y la m\u00e9dula espinal. Esto puede provocar debilidad muscular, par\u00e1lisis y muerte. No hay cura a\u00fan para la ELA, sin embargo, hay tratamientos disponibles, incluida la terapia con C\u00e9lulas Madre.\r\n\r\nSe ha demostrado que son eficaces para combatir los efectos de la ELA y pueden ayudar a mejorar la funci\u00f3n muscular y prolongar la vida de los pacientes.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a36fe7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a36fe7a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e093feb\" data-id=\"e093feb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee3669e elementor-widget elementor-widget-heading\" data-id=\"ee3669e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 elegir el Stem Cells Transplant Institute en las Bahamas?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c0c71 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f1c0c71\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">En el Stem Cells Transplant Institute, nuestros m\u00e9dicos est\u00e1n acreditados por la Academia Estadounidense de Medicina Regenerativa y Antienvejecimiento y tienen a\u00f1os de experiencia en la terapia con c\u00e9lulas madre.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Colaboramos con los principales investigadores, laboratorios y cl\u00ednicas de todo el mundo para mantenernos al d\u00eda con los \u00faltimos avances en tecnolog\u00eda de c\u00e9lulas madre.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuestros m\u00e9dicos tambi\u00e9n son miembros de la Sociedad Internacional para la Aplicaci\u00f3n de C\u00e9lulas Madre.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuestro CEO y fundador, el Dr. Mesen, es el Director de la ISSCA - Sociedad para Am\u00e9rica Central y el Caribe.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Utilizamos procedimientos de vanguardia que combinan c\u00e9lulas madre mesenquimales derivadas de tejido adiposo con factores de crecimiento ricos en plaquetas para mejorar la eficacia y mejorar los resultados.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tambi\u00e9n utilizamos c\u00e9lulas madre mesenquimales adultas derivadas del cord\u00f3n umbilical humano o del tejido del propio paciente. Al hacerlo, podemos asegurar a nuestros pacientes las c\u00e9lulas madre mesenquimales de la m\u00e1s alta calidad disponible.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Stem Cells Transplant Institute en Bahamas Bienvenidos al Stem Cells Transplant Institute en Bahamas. Nuestra misi\u00f3n es brindar un tratamiento de primer nivel a los pacientes que utilizan terapia con C\u00e9lulas Madre. Nuestra cl\u00ednica en Costa Rica, est\u00e1 dirigida por el Doctor Leslie Mes\u00e9n, uno de los m\u00e9dicos expertos m\u00e1s destacados en terapia con C\u00e9lulas [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-26415","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages\/26415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/comments?post=26415"}],"version-history":[{"count":0,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages\/26415\/revisions"}],"wp:attachment":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/media?parent=26415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}