{"id":2284,"date":"2016-01-03T16:49:03","date_gmt":"2016-01-03T16:49:03","guid":{"rendered":"\/?page_id=2284"},"modified":"2022-04-11T19:53:02","modified_gmt":"2022-04-12T01:53:02","slug":"esclerosis-multiple","status":"publish","type":"page","link":"https:\/\/stemcells.suwebcr.com\/es\/esclerosis-multiple\/","title":{"rendered":"Esclerosis M\u00faltiple"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2284\" class=\"elementor elementor-2284 elementor-2197\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9499bc0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9499bc0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.8000000000000000444089209850062616169452667236328125,&quot;sizes&quot;:[]},&quot;shape_divider_top&quot;:&quot;pyramids&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;pyramids&quot;,&quot;background_motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,40.6L643.1,24L333.9,93.8L0.1,1H0v99h1000V1\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,44.1L643.1,27.2L333.8,98L0,3.8V0l1000,0v3.9\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3f67f9\" data-id=\"c3f67f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-978c898 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978c898\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-70a8804\" data-id=\"70a8804\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d8060 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e0d8060\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Regenerar. Reparar. Restaurar.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110a3f0 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"110a3f0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Terapia con c\u00e9lulas madres para Esclerosis Multiple (EM) y desordenes del sistema nervioso.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a9cb31\" data-id=\"7a9cb31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b82d5 elementor-widget elementor-widget-global elementor-global-23261 elementor-widget-html\" data-id=\"17b82d5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe\r\n  src=\"https:\/\/crm.wordpress-1021233-3607520.cloudwaysapps.com\/widget\/form\/virWvBeuIrgOaDQh6svg\"\r\n  style=\"width:100%;height:100%;border:none;border-radius:0px\"\r\n  id=\"inline-virWvBeuIrgOaDQh6svg\" \r\n  data-layout=\"{'id':'INLINE'}\"\r\n  data-trigger-type=\"alwaysShow\"\r\n  data-trigger-value=\"\"\r\n  data-activation-type=\"alwaysActivated\"\r\n  data-activation-value=\"\"\r\n  data-deactivation-type=\"neverDeactivate\"\r\n  data-deactivation-value=\"\"\r\n  data-form-name=\"Stem Cells Webform - Dark (Spanish)\"\r\n  data-height=\"620\"\r\n  data-layout-iframe-id=\"inline-virWvBeuIrgOaDQh6svg\"\r\n  data-form-id=\"virWvBeuIrgOaDQh6svg\"\r\n  title=\"Stem Cells Webform - Dark (Spanish)\"\r\n      >\r\n<\/iframe>\r\n<script src=\"https:\/\/crm.wordpress-1021233-3607520.cloudwaysapps.com\/js\/form_embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a9e914 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8a9e914\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7692835\" data-id=\"7692835\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8441f4f elementor-position-left elementor-widget__width-initial elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"8441f4f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#help\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/690150.png\" class=\"attachment-full size-full wp-image-24511\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/690150.png 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/690150-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\"><a href=\"#help\">\u00bfC\u00f3mo ayudan  las c\u00e9lulas madre?<\/a><\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-37b6338\" data-id=\"37b6338\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ebdde7 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"8ebdde7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#protocol\" tabindex=\"-1\"><img decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/1067182-200.png\" class=\"attachment-full size-full wp-image-24509\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/1067182-200.png 216w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/1067182-200-150x150.png 150w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\"><a href=\"#protocol\">Protocolo de tratamiento<\/a><\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ffc4a28\" data-id=\"ffc4a28\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e12de1 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"7e12de1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#why-sti\" tabindex=\"-1\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/costa-rica.png\" class=\"attachment-full size-full wp-image-24507\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/costa-rica.png 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/costa-rica-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\"><a href=\"#why-sti\">\u00bfPor qu\u00e9 Costa Rica?<\/a><\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-713cb7e\" data-id=\"713cb7e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320cb47 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"320cb47\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#why-sti\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/celula.png\" class=\"attachment-full size-full wp-image-24505\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\"><a href=\"#why-sti\">\u00bfPor qu\u00e9 Stem Cells Transplant Institute?<\/a><\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-896874b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"896874b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4a90199 elementor-hidden-mobile elementor-hidden-tablet\" data-id=\"4a90199\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fd6932 elementor-widget elementor-widget-image\" data-id=\"2fd6932\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2022\/03\/hands-hold-mri-scan-of-head-neck-and-brain-of-pat-2021-08-29-11-13-57-utc.jpg\" class=\"attachment-large size-large wp-image-26192\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2022\/03\/hands-hold-mri-scan-of-head-neck-and-brain-of-pat-2021-08-29-11-13-57-utc.jpg 600w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2022\/03\/hands-hold-mri-scan-of-head-neck-and-brain-of-pat-2021-08-29-11-13-57-utc-300x300.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2022\/03\/hands-hold-mri-scan-of-head-neck-and-brain-of-pat-2021-08-29-11-13-57-utc-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e62bcb elementor-widget elementor-widget-image\" data-id=\"3e62bcb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/Autism-Stem-Cells.jpg\" class=\"attachment-large size-large wp-image-24919\" alt=\"Autism Stem Cells\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/Autism-Stem-Cells.jpg 350w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/Autism-Stem-Cells-300x300.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2021\/09\/Autism-Stem-Cells-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1f33397\" data-id=\"1f33397\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a9c0aa elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-video\" data-id=\"4a9c0aa\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=8M0HvV_CD88&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-79ead5d\" data-id=\"79ead5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bab5521 elementor-widget elementor-widget-text-editor\" data-id=\"bab5521\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa Esclerosis M\u00faltiple afecta al Sistema Nervioso Central.\r\n\r\nEl <em>Stem Cells Transplant Institute <\/em>recomienda el uso de C\u00e9lulas Madre Mesenquimales, derivadas, cultivadas y expandidas del tejido del cord\u00f3n umbilical, para el tratamiento de enfermedades neurol\u00f3gicas, incluida la Esclerosis M\u00faltiple.\r\n\r\n<strong>El tratamiento puede ayudar a mejorar los siguientes s\u00edntomas de la Esclerosis M\u00faltiple:<\/strong>\r\n<ul>\r\n \t<li>Alteraciones Visuales<\/li>\r\n \t<li>P\u00e9rdida del Equilibrio<\/li>\r\n \t<li>Falta de Coordinaci\u00f3n<\/li>\r\n \t<li>Arrastre en el Habla<\/li>\r\n \t<li>Temblores<\/li>\r\n \t<li>Entumecimiento<\/li>\r\n \t<li>Cansancio extremo<\/li>\r\n \t<li>Problemas de memoria y concentraci\u00f3n. Par\u00e1lisis<\/li>\r\n \t<li>Ceguera<\/li>\r\n \t<li>Problemas de vejiga e intestino<\/li>\r\n \t<li>Disfunciones Sexuales<\/li>\r\n \t<li>Espasticidad Muscular<\/li>\r\n \t<li>Sensibilidad al Calor<\/li>\r\n \t<li>Alteraciones Emocionales<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e58636b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e58636b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fa21ef7\" data-id=\"fa21ef7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fc159f elementor-widget elementor-widget-text-editor\" data-id=\"6fc159f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfQu\u00e9 sabemos de la Esclerosis M\u00faltiple?<\/h2><p>La Esclerosis M\u00faltiple (EM) es un grupo de trastornos cr\u00f3nicos inmunomediados en los que el sistema inmunitario ataca por error, al tejido sano del Sistema Nervioso Central.<\/p><p>La EM se caracteriza por episodios recurrentes de desmielinizaci\u00f3n inflamatoria focal que provocan s\u00edntomas neurol\u00f3gicos.<\/p><p>La EM afecta a m\u00e1s de 2,5 millones de personas en todo el mundo y, aunque puede afectar a cualquier persona a cualquier edad, la mayor\u00eda de los diagn\u00f3sticos ocurre entre los 20 y 50 a\u00f1os.<\/p><p>Los axones del cerebro y la m\u00e9dula espinal son fibras nerviosas que transmiten informaci\u00f3n a diferentes neuronas, m\u00fasculos y gl\u00e1ndulas del cuerpo.<\/p><p>La Esclerosis M\u00faltiple se diagnostica cuando el sistema inmunitario ataca y da\u00f1a la vaina protectora de mielina, lo que afecta la capacidad del sistema nervioso central para comunicarse con el resto del cuerpo.<\/p><p>Por lo general, los nervios comienzan a degenerarse y pueden da\u00f1arse de forma permanente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-628aaaf\" data-id=\"628aaaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ce93f9 elementor-widget elementor-widget-text-editor\" data-id=\"0ce93f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>El \u00f3 los s\u00edntomas exactos est\u00e1n relacionados con las \u00e1reas que han sido afectadas.<\/p><p>La terapia convencional reduce o previene los episodios inflamatorios, pero tiene poco impacto en el curso de la progresi\u00f3n de la Esclerosis M\u00faltiple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf08296 elementor-widget elementor-widget-image\" data-id=\"cf08296\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"424\" src=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/19185.jpg\" class=\"attachment-large size-large wp-image-7106\" alt=\"\" srcset=\"https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/19185.jpg 1000w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/19185-300x159.jpg 300w, https:\/\/stemcells.suwebcr.com\/wp-content\/uploads\/2019\/04\/19185-768x407.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-394e767 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"394e767\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b157f1\" data-id=\"2b157f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f73bf1 elementor-widget elementor-widget-text-editor\" data-id=\"4f73bf1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Hay 4 tipos de Esclerosis M\u00faltiple:<\/strong><\/h2><p><strong>Esclerosis M\u00faltiple Recurrente-Remitente<\/strong><\/p><p>Es el tipo m\u00e1s com\u00fan de Esclerosis M\u00faltiple. Los pacientes experimentan reca\u00eddas y per\u00edodos de estabilidad intermedios.<\/p><p><strong>Esclerosis M\u00faltiple Progresiva Secundaria <\/strong><\/p><p>Se diagnostica cuando los problemas causados \u200b\u200bpor una exacerbaci\u00f3n no se resuelven por completo durante una remisi\u00f3n. Esto ocurre a menudo en pacientes a los que inicialmente se les diagnostic\u00f3 la primera.<\/p><p><strong>Esclerosis M\u00faltiple Progresiva Secundaria <\/strong><\/p><p>Progresa con el tiempo, sin episodios de remisi\u00f3n o mejor\u00eda de los s\u00edntomas.<\/p><p><strong>Esclerosis M\u00faltiple Progresiva Recidivante <\/strong><\/p><p>Se diagnostica cuando los pacientes experimentan un aumento de los s\u00edntomas con el tiempo, as\u00ed como episodios intermitentes de remisi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b860f8 elementor-widget elementor-widget-text-editor\" data-id=\"7b860f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfCu\u00e1l es el protocolo para el Tratamiento de la Esclerosis M\u00faltiple en el Stem Cells Transplant Institute?<\/h2><p>El Stem Cells Transplant Institute recomienda el uso de hUC-MSC para el tratamiento de la Esclerosis M\u00faltiple. El protocolo espec\u00edfico lo decidir\u00e1 el m\u00e9dico tratante, una vez que el paciente haya aportado su historia cl\u00ednica y haya sido evaluada su condici\u00f3n. El protocolo descrito a continuaci\u00f3n solo pretende servir como una gu\u00eda.<\/p><ul><li>La duraci\u00f3n del tratamiento puede durar 4 d\u00edas y 5 noches o 6 d\u00edas y 7 noches, dependiendo de la gravedad de la enfermedad.<\/li><li>El primer d\u00eda incluye examen f\u00edsico y an\u00e1lisis de sangre.120 millones de C\u00e9lulas Madre Mesenquimales cultivadas y expandidas a partir del tejido del cord\u00f3n umbilical humano (un total de 480 millones de C\u00e9lulas Madre<\/li><li>\u00a0Mesenquimales en 4 d\u00edas o un total de 720 millones en 6 d\u00edas).<\/li><li>Las inyecciones se administran por v\u00eda intratecal e intravenosa.<\/li><li>Terapia Antioxidante con vitamina C y Glutati\u00f3n con cada Tratamiento con C\u00e9lulas Madre.<\/li><li>Ozonoterapia con cada Tratamiento con C\u00e9lulas Madre.<\/li><li>Terapia de Plasma Rico en Plaquetas con cada Tratamiento con C\u00e9lulas Madre.<\/li><li>Para los casos m\u00e1s graves, puede haber un ciclo de quimioterapia de hasta 3 d\u00edas antes de iniciar la Terapia con C\u00e9lulas Madre.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d67a49\" data-id=\"5d67a49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b5be37 elementor-widget elementor-widget-text-editor\" data-id=\"6b5be37\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfQu\u00e9 est\u00e1n investigando los m\u00e9dicos y c\u00f3mo puede el Tratamiento de las C\u00e9lulas Madre mejorar los s\u00edntomas de la Esclerosis M\u00faltiple?<\/h2><p>Los investigadores est\u00e1n evaluando la forma m\u00e1s eficaz de utilizar la terapia con C\u00e9lulas Madre para prevenir o reparar la mielina y la vaina de la mielina da\u00f1adas.<\/p><p>Algunos estudios han mostrado resultados positivos, en pacientes con Esclerosis M\u00faltiple Recurrente Remitente, usando quimioterapia primero para destruir el sistema inmunitario del paciente, seguido de terapia con C\u00e9lulas Madre para reconstruir dicho sistema y que ya no ataque la mielina.<\/p><p>Se han encontrado ensayos cl\u00ednicos en donde se utiliza las C\u00e9lulas Madre Mesenquimales para curar el da\u00f1o al sistema nervioso y mejorar los s\u00edntomas de la Esclerosis M\u00faltiple, lo que resulta en una mejor calidad de vida.<\/p><p>Las C\u00e9lulas Madre Mesenquimales producen: 1. Prote\u00ednas que ayudan a las neuronas a crecer y sobrevivir; 2. Factores Angiog\u00e9nicos que ayudan en la curaci\u00f3n, crecimiento, desarrollo y mantenimiento de los vasos sangu\u00edneos; y 3. Sustancias Inmunomoduladoras que ayudan a reparar los nervios da\u00f1ados 2 y 3.<\/p><p>Los investigadores m\u00e9dicos est\u00e1n trabajando para desarrollar Tratamientos con C\u00e9lulas Madre que restablezcan los nervios lesionados o da\u00f1ados.<\/p><p>Para los pacientes con Esclerosis M\u00faltiple, las C\u00e9lulas Madre reparan las \u00e1reas da\u00f1adas por la desmielinizaci\u00f3n y generan<\/p><p>c\u00e9lulas nuevas y saludables, lo que previene da\u00f1os mayores y reduce los s\u00edntomas.<\/p><p>Los resultados de la investigaci\u00f3n preliminar, que eval\u00faa la seguridad y la eficacia del Trasplante Aut\u00f3logo de C\u00e9lulas Madre para tratar a pacientes con Esclerosis M\u00faltiple, parecen prometedores.<\/p><p>Se publicaron los resultados de un estudio piloto realizado por investigadores de Cleveland Clinic para evaluar la viabilidad, seguridad y tolerabilidad del Trasplante Aut\u00f3logo de C\u00e9lulas Madre Mesenquimales en pacientes con Esclerosis M\u00faltiple del tipo Remitente-Recurrente, como tambi\u00e9n con Esclerosis M\u00faltiple Progresivo Secundario y se encontr\u00f3 que son factibles, seguros y bien tolerados.<\/p><p>Investigadores M\u00e9dicos en Barcelona, \u200b\u200bEspa\u00f1a, evaluaron la eficacia de las C\u00e9lulas Madre Mesenquimales en pacientes que no respond\u00edan a la terapia convencional y tambi\u00e9n encontraron que el Trasplante de C\u00e9lulas Madre result\u00f3 seguro y efectivo.<\/p><p>Hubo menos lesiones, una reducci\u00f3n en el volumen de la lesi\u00f3n T2 y una reducci\u00f3n en el grosor de la capa de fibras nerviosas de la retina, en el tiempo entre 6 meses y 1 a\u00f1o.<\/p><p>La investigaci\u00f3n innovadora que eval\u00faa la seguridad y la eficacia del Trasplante de C\u00e9lulas Madre para el Tratamiento de la Esclerosis M\u00faltiple est\u00e1 progresando significativamente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9aff2c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aff2c0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-925a80c\" data-id=\"925a80c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2659262 elementor-widget elementor-widget-text-editor\" data-id=\"2659262\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfCu\u00e1les son las ventajas de las C\u00e9lulas Madre Mesenquimales del cord\u00f3n umbilical humano?<\/h2><ul><li>Contiene hasta 10 veces m\u00e1s C\u00e9lulas Madre que la m\u00e9dula \u00f3sea o las c\u00e9lulas madre derivadas del tejido adiposo<\/li><li>Las hUC-MSC tienen propiedades inmunosupresoras e inmunomoduladoras que permiten su uso en cualquier individuo sin ser rechazadas. No es necesaria la compatibilidad con el Ant\u00edgeno Leucocitario Humano<\/li><li>Mayor capacidad de proliferaci\u00f3n que las C\u00e9lulas Madre Aut\u00f3logas Adultas<\/li><li>Se regeneran a un ritmo muy r\u00e1pido. Son j\u00f3venes y muy adaptables<\/li><li>No han sido impactados por el proceso de envejecimiento<\/li><li>No han sido afectados por toxinas ambientales<\/li><li>Las C\u00e9lulas Madre del cord\u00f3n umbilical se pueden administrar varias veces en el transcurso de los d\u00edas<\/li><li>Elimina la necesidad de recolectar C\u00e9lulas Madre de la grasa o del hueso de la cadera del paciente, lo que reduce el dolor y el tiempo de recuperaci\u00f3n<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a9c4b94\" data-id=\"a9c4b94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5002bec elementor-widget elementor-widget-text-editor\" data-id=\"5002bec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfCu\u00e1les son los desaf\u00edos?<\/h2><p>Las enfermedades autoinmunes como la Esclerosis M\u00faltiple, son dif\u00edciles de tratar porque necesita que el propio sistema inmunitario combata las infecciones, por lo que no es posible bloquear por completo el sistema inmunitario del paciente.<\/p><ul><li>Cada paciente es diferente.<\/li><li>La enfermedad presenta diferentes clasificaciones.<\/li><li>Los cient\u00edficos a\u00fan no tienen certeza de c\u00f3mo se forma la vaina de mielina.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7879c391 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7879c391\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c2b44fd\" data-id=\"6c2b44fd\" data-element_type=\"column\" id=\"protocol\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a6c3a26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a6c3a26\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e837515 animated-slow elementor-invisible\" data-id=\"4e837515\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45ddb44d elementor-widget elementor-widget-spacer\" data-id=\"45ddb44d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48c04a8a elementor-widget elementor-widget-heading\" data-id=\"48c04a8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">donaciones de cordon umbilical<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3493e24a animated-slow elementor-invisible\" data-id=\"3493e24a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b94eb85 elementor-widget elementor-widget-spacer\" data-id=\"1b94eb85\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7e927d elementor-widget elementor-widget-heading\" data-id=\"7d7e927d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Administraci\u00f3n intravenosa<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3157c6c1 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3157c6c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfC\u00f3mo se recolectan las C\u00e9lulas Madre?<\/h2><p>Las C\u00e9lulas Madre del cord\u00f3n umbilical, que se derivan exclusivamente de donaciones, son las \u00fanicas C\u00e9lulas Madre con las que trabajamos. Las C\u00e9lulas Madre del cord\u00f3n umbilical se recolectan despu\u00e9s de que el o los padres hayan dado su consentimiento y despu\u00e9s del nacimiento del beb\u00e9.<\/p><p>La recolecci\u00f3n sigue estrictos protocolos \u00e9ticos que garantizan que las C\u00e9lulas Madre provengan de fuentes seguras y confiables, mediante un procedimiento no invasivo, simple e indoloro.<\/p><p>Una vez recolectada, la sangre del cord\u00f3n umbilical se analiza para detectar enfermedades.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-375ca999 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"375ca999\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfC\u00f3mo son administradas las C\u00e9lulas Madre?<\/h2>\r\nLas C\u00e9lulas Madre son administradas por una inyecci\u00f3n v\u00eda intravenosa e intratecal.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60999798 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60999798\" data-element_type=\"section\" id=\"why-sti\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3150bfca\" data-id=\"3150bfca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5323964b elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5323964b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Acerca del <em>Stem Cells Transplant Institute<\/em><\/h2><p>Costa Rica tiene uno de los mejores sistemas de salud del mundo, clasificado adem\u00e1s, entre los m\u00e1s altos para el turismo m\u00e9dico.<\/p><p>Utilizando las tecnolog\u00edas m\u00e1s avanzadas, el equipo de expertos del <em>Stem Cells Transplant Institute<\/em> cree en el potencial de la terapia con C\u00e9lulas Madre para el tratamiento de la Esclerosis M\u00faltiple.<\/p><p>Estamos comprometidos a brindar un servicio personalizado y de la m\u00e1s alta calidad de atenci\u00f3n para cada paciente.<\/p><p>Comun\u00edquese con los expertos del <em>Stem Cells Transplant Institute<\/em> para poder decidir si el trasplante de C\u00e9lulas Madre es una opci\u00f3n de tratamiento viable para usted.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fffe67e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fffe67e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f8373d\" data-id=\"0f8373d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0a42a6 elementor-widget elementor-widget-heading\" data-id=\"c0a42a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Referencias cient\u00edficas:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab73bac elementor-widget elementor-widget-text-editor\" data-id=\"ab73bac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t1. Panagiotis Douvaras et al., Efficient Generation of Myelinating Oligodendrocytes from PrimaryProgressive Multiple Sclerosis Patients by Induced Pluripotent Stem Cells. Stem Cell Reports j Vol. 3 j 250\u2013259 j August 12, 2014.\r\n2. Cell Death Discovery (2016) 2, e16055; doi:10.1038\/cddiscovery.2016.55; published online 11 July 2016 Mesenchymal stem cells to treat diabetic neuropathy: a long and strenuous way from bench to the clinic JY Zhou\r\n3. Vickers RE et al., A preliminary report on stem cell therapy for neuropathic pain in humans. J Pain Res. 2014; 7: 255\u2013263. Published online 2014 May 8.\r\n4. Jeffrey A Cohen et al.,Pilot trial of intravenous autologous culture-expanded mesenchymal stem cell\u00a0\u00a0 transplantation in multiple sclerosis Multiple Sclerosis Journal 1\u201311DOI: 10.1177\/1352458517703802.\r\n5. Sara Llufriu et al.,Randomized Placebo-Controlled Phase II Trial of Autologous Mesenchymal Stem Cells in Multiple Sclerosis. PLoS ONE 9(12): e113936. doi:10.1371\/ journal.pone.0113936\r\n6. Riordan, NH. et. al., Clinical feasibility of umbilical cord tissue-derived mesenchymal stem cells in the treatment of multiple sclerosis. J Transl Med. 2018, Mar 9; 16:57\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Regenerar. Reparar. Restaurar. Terapia con c\u00e9lulas madres para Esclerosis Multiple (EM) y desordenes del sistema nervioso. \u00bfC\u00f3mo ayudan las c\u00e9lulas madre? Protocolo de tratamiento \u00bfPor qu\u00e9 Costa Rica? \u00bfPor qu\u00e9 Stem Cells Transplant Institute? https:\/\/www.youtube.com\/watch?v=8M0HvV_CD88La Esclerosis M\u00faltiple afecta al Sistema Nervioso Central. El Stem Cells Transplant Institute recomienda el uso de C\u00e9lulas Madre Mesenquimales, derivadas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2875,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2284","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages\/2284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/comments?post=2284"}],"version-history":[{"count":0,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/pages\/2284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/media\/2875"}],"wp:attachment":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/media?parent=2284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}