{"id":197,"count":9,"description":"","link":"https:\/\/stemcells.suwebcr.com\/es\/category\/parkinson\/","name":"Parkinson","slug":"parkinson","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/categories\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stemcells.suwebcr.com\/es\/wp-json\/wp\/v2\/posts?categories=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}